{"id":5656,"date":"2025-10-28T09:47:46","date_gmt":"2025-10-28T08:47:46","guid":{"rendered":"https:\/\/www.lasgabias.es\/lasgabias\/?p=5656"},"modified":"2025-10-28T09:52:23","modified_gmt":"2025-10-28T08:52:23","slug":"el-ayuntamiento-de-las-gabias-impulsa-una-ambiciosa-renovacion-normativa-para-mejorar-las-condiciones-laborales-y-modernizar-la-gestion-del-personal-publico","status":"publish","type":"post","link":"https:\/\/www.lasgabias.es\/lasgabias\/el-ayuntamiento-de-las-gabias-impulsa-una-ambiciosa-renovacion-normativa-para-mejorar-las-condiciones-laborales-y-modernizar-la-gestion-del-personal-publico\/","title":{"rendered":"El Ayuntamiento de Las Gabias impulsa una ambiciosa renovaci\u00f3n normativa para mejorar las condiciones laborales y modernizar la gesti\u00f3n del personal p\u00fablico"},"content":{"rendered":"<p><span style=\"color: #000000\"><strong><i>El equipo de gobierno aprueba el nuevo Reglamento de Mesas de Negociaci\u00f3n, el Reglamento del Teletrabajo y la denuncia del antiguo Convenio Colectivo, dando paso a una actualizaci\u00f3n integral de los derechos y deberes del personal municipal<\/i><\/strong><\/span><\/p>\n<p><span style=\"color: #000000\"><i><strong>Las nuevas medidas consolidar\u00e1n un modelo de administraci\u00f3n moderna, transparente y adaptada a la realidad actual, que refuerza la conciliaci\u00f3n, la eficiencia y la calidad del empleo p\u00fablico local<\/strong> <\/i><\/span><\/p>\n<p>El Ayuntamiento de Las Gabias ha aprobado en la sesi\u00f3n plenaria de octubre una bater\u00eda de medidas clave en materia de personal que impulsar\u00e1 la reforma de la organizaci\u00f3n interna y de las condiciones laborales de la plantilla municipal.<\/p>\n<p>Con estas tres iniciativas, aprobadas por unanimidad en la sesi\u00f3n plenaria de octubre, el equipo de gobierno liderado por la alcaldesa Meri S\u00e1daba reafirma su compromiso con la modernizaci\u00f3n de la gesti\u00f3n p\u00fablica, la transparencia en las relaciones laborales y la mejora del bienestar de los empleados municipales, abriendo una nueva etapa de di\u00e1logo y actualizaci\u00f3n normativa.<\/p>\n<p>El nuevo Reglamento de Mesas de Negociaci\u00f3n establece un marco ordenado, participativo y garantista para el di\u00e1logo entre la corporaci\u00f3n y los representantes sindicales, asegurando la correcta tramitaci\u00f3n de los acuerdos laborales y la participaci\u00f3n activa de los trabajadores en las decisiones que afectan a su d\u00eda a d\u00eda.<\/p>\n<p>Por su parte, el Reglamento del Teletrabajo \u2014pionero en el \u00e1mbito local\u2014 permitir\u00e1 compatibilizar la prestaci\u00f3n de servicios p\u00fablicos con la conciliaci\u00f3n familiar, regulando de forma clara los requisitos, derechos, deberes y modalidades de esta nueva forma de trabajo. La norma reconoce hasta dos d\u00edas semanales de teletrabajo, priorizando su concesi\u00f3n a quienes tengan necesidades especiales o familiares, e incorpora garant\u00edas de control, eficiencia y derecho a la desconexi\u00f3n digital.<\/p>\n<p>Finalmente, la denuncia del Convenio Colectivo y del Acuerdo Marco vigentes desde hace m\u00e1s de una d\u00e9cada supone el punto de partida para la negociaci\u00f3n de un nuevo marco laboral adaptado a la legislaci\u00f3n actual y a la realidad de la plantilla municipal. Este proceso abrir\u00e1 un periodo de di\u00e1logo con los representantes sindicales con el objetivo de alcanzar un acuerdo que refuerce la estabilidad, la equidad y la motivaci\u00f3n del personal del Ayuntamiento.<\/p>\n<p>El Concejal de Presidencia, Personal, Juventud y Desarrollo, Mariano Delgado, ha comentado la importancia de estas medidas para el buen funcionamiento de la administraci\u00f3n local: \u201cLas mejoras de la calidad laboral, deben de materializarse con medidas reales y tangibles, como las que ya ha puesto en funcionamiento este equipo de gobierno\u201d, record\u00f3 el segundo Teniente de Alcaldesa, subrayando la \u201creducci\u00f3n de la temporalidad, el 100% de estabilidad laboral, la ampliaci\u00f3n de jornadas parciales a jornadas completas o la aprobaci\u00f3n de la jornada de 35 horas\u201d.<\/p>\n<p>La alcaldesa de Las Gabias, Meri S\u00e1daba, ha destacado que \u201cestas medidas suponen un paso decisivo hacia una administraci\u00f3n m\u00e1s justa, moderna y humanizada. Nuestro compromiso con el personal del Ayuntamiento es firme: queremos que trabajen en las mejores condiciones posibles, con normas claras, actualizadas y que reconozcan el valor de su esfuerzo diario\u201d.<\/p>\n<p>S\u00e1daba subray\u00f3 tambi\u00e9n que \u201ceste proceso de modernizaci\u00f3n no es solo una cuesti\u00f3n interna: mejora la calidad del servicio que prestamos a nuestros vecinos, porque un personal motivado, formado y bien tratado es la mejor garant\u00eda de una administraci\u00f3n eficaz y cercana con sus vecinos\u201d.<\/p>\n<p>Con esta triple acci\u00f3n \u2014negociaci\u00f3n, actualizaci\u00f3n normativa y adaptaci\u00f3n tecnol\u00f3gica\u2014, el Ayuntamiento de Las Gabias consolida una gesti\u00f3n de recursos humanos moderna, transparente y centrada en las personas, reafirmando el compromiso del equipo de gobierno con la mejora continua del servicio p\u00fablico y el bienestar de quienes lo hacen posible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de gobierno aprueba el nuevo Reglamento de Mesas de Negociaci\u00f3n, el Reglamento del Teletrabajo y la denuncia del antiguo Convenio Colectivo, dando paso a una actualizaci\u00f3n integral de los derechos y deberes del personal municipal Las nuevas medidas consolidar\u00e1n un modelo de administraci\u00f3n moderna, transparente y adaptada a la realidad actual, que refuerza&hellip;<\/p>\n","protected":false},"author":237,"featured_media":5659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[49,89],"tags":[],"class_list":["post-5656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personal","category-presidencia","category-49","category-89","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/posts\/5656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/users\/237"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/comments?post=5656"}],"version-history":[{"count":3,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/posts\/5656\/revisions"}],"predecessor-version":[{"id":5662,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/posts\/5656\/revisions\/5662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/media\/5659"}],"wp:attachment":[{"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/media?parent=5656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/categories?post=5656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasgabias.es\/lasgabias\/wp-json\/wp\/v2\/tags?post=5656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}